{"id":403,"date":"2024-07-24T09:32:46","date_gmt":"2024-07-24T09:32:46","guid":{"rendered":"https:\/\/roaldagroup.com\/aviso-legal\/"},"modified":"2025-10-09T07:28:42","modified_gmt":"2025-10-09T07:28:42","slug":"aviso-legal","status":"publish","type":"page","link":"https:\/\/roaldagroup.com\/ca\/aviso-legal\/","title":{"rendered":"Aviso legal"},"content":{"rendered":"<section class=\"text_content_text_1_1 background-1-light\" data-block-id=\"6a56f419774406a56f41977441\">\r\n    <div class=\"container\">\r\n        <div class=\"row\">\r\n            <div class=\"col\">\r\n                <div class=\"content-theme\">\r\n                                        <div class=\"texto color-1-headings-dark tamano7\">\r\n                        <h2 style='text-align: center'>AVISO LEGAL Y CONDICIONES GENERALES DE USO <br \/>\n        https:\/\/roaldagroup.com\/ca\/<\/h2>\n<p>        &nbsp;<\/p>\n<h3>I. INFORMACI\u00d3N GENERAL<\/h3>\n<p>En cumplimiento con el deber de informaci\u00f3n dispuesto en la Ley 34\/2002 de Servicios de la Sociedad de la Informaci\u00f3n y el Comercio Electr\u00f3nico (LSSI-CE) de 11 de julio, se facilitan a continuaci\u00f3n los siguientes datos de informaci\u00f3n general de este sitio web:<\/p>\n<p>La titularidad de este sitio web, https:\/\/roaldagroup.com\/ca\/ (en adelante, Sitio Web) la ostenta:   Leboso de Brito, con NIF: 55180937G, y cuyos datos de contacto son:<\/p>\n<p>Direcci\u00f3n: Plaza vapor ventall\u00f3, 08221, Tarrassa<\/p>\n<p>Tel\u00e9fono de contacto: 697326428<\/p>\n<p>Email de contacto: <\/p>\n<p>        &nbsp;<\/p>\n<h3>II. T\u00c9RMINOS Y CONDICIONES GENERALES DE USO<\/h3>\n<h4>El objeto de las condiciones: El Sitio Web<\/h4>\n<p>El objeto de las presentes Condiciones Generales de Uso (en adelante, Condiciones) es regular el acceso y la utilizaci\u00f3n del Sitio Web. A los efectos de las presentes Condiciones se entender\u00e1 como Sitio Web: la apariencia externa de los interfaces de pantalla, tanto de forma est\u00e1tica como de forma din\u00e1mica, es decir, el \u00e1rbol de navegaci\u00f3n; y todos los elementos integrados tanto en los interfaces de pantalla como en el \u00e1rbol de navegaci\u00f3n (en adelante, Contenidos) y todos aquellos servicios o recursos en l\u00ednea que en su caso ofrezca a los Usuarios (en adelante, Servicios).<\/p>\n<p>Blog de  se reserva la facultad de modificar, en cualquier momento, y sin aviso previo, la presentaci\u00f3n y configuraci\u00f3n del Sitio Web y de los Contenidos y Servicios que en \u00e9l pudieran estar incorporados. El Usuario reconoce y acepta que en cualquier momento Blog de  pueda interrumpir, desactivar y\/o cancelar cualquiera de estos elementos que se integran en el Sitio Web o el acceso a los mismos.<\/p>\n<p>El acceso al Sitio Web por el Usuario tiene car\u00e1cter libre y, por regla general, es gratuito sin que el Usuario tenga que proporcionar una contraprestaci\u00f3n para poder disfrutar de ello, salvo en lo relativo al coste de conexi\u00f3n a trav\u00e9s de la red de telecomunicaciones suministrada por el proveedor de acceso que hubiere contratado el Usuario.<br \/>\n        La utilizaci\u00f3n de alguno de los Contenidos o Servicios del Sitio Web podr\u00e1 hacerse mediante la suscripci\u00f3n o registro previo del Usuario.<\/p>\n<h4>El Usuario<\/h4>\n<p>\n        El acceso, la navegaci\u00f3n y uso del Sitio Web, as\u00ed como por los espacios habilitados para interactuar entre los Usuarios, y el Usuario y Blog de , como los comentarios y\/o espacios de blogging, confiere la condici\u00f3n de Usuario, por lo que se aceptan, desde que se inicia la navegaci\u00f3n por el Sitio Web, todas las Condiciones aqu\u00ed establecidas, as\u00ed como sus ulteriores modificaciones, sin perjuicio de la aplicaci\u00f3n de la correspondiente normativa legal de obligado cumplimiento seg\u00fan el caso. Dada la relevancia de lo anterior, se recomienda al Usuario leerlas cada vez que visite el Sitio Web.\n        <\/p>\n<p>\n        El Sitio Web de Blog de  proporciona gran diversidad de informaci\u00f3n, servicios y datos. El Usuario asume su responsabilidad para realizar un uso correcto del Sitio Web. Esta responsabilidad se extender\u00e1 a:\n        <\/p>\n<ul>\n<li>Un uso de la informaci\u00f3n, Contenidos y\/o Servicios y datos ofrecidos por Blog de  sin que sea contrario a lo dispuesto por las presentes Condiciones, la Ley, la moral o el orden p\u00fablico, o que de cualquier otro modo puedan suponer lesi\u00f3n de los derechos de terceros o del mismo funcionamiento del Sitio Web.<\/li>\n<li>La veracidad y licitud de las informaciones aportadas por el Usuario en los formularios extendidos por Blog de  para el acceso a ciertos Contenidos o Servicios ofrecidos por el Sitio Web. En todo caso, el Usuario notificar\u00e1 de forma inmediata a Blog de  acerca de cualquier hecho que permita el uso indebido de la informaci\u00f3n registrada en dichos formularios, tales como, pero no solo, el robo, extrav\u00edo, o el acceso no autorizado a identificadores y\/o contrase\u00f1as, con el fin de proceder a su inmediata cancelaci\u00f3n.<\/li>\n<\/ul>\n<p>\n        Blog de  se reserva el derecho de retirar todos aquellos comentarios y aportaciones que vulneren la ley, el respeto a la dignidad de la persona, que sean discriminatorios, xen\u00f3fobos, racistas, pornogr\u00e1ficos, spamming, que atenten contra la juventud o la infancia, el orden o la seguridad p\u00fablica o que, a su juicio, no resultaran adecuados para su publicaci\u00f3n.\n        <\/p>\n<p>\n        En cualquier caso, Blog de  no ser\u00e1 responsable de las opiniones vertidas por los Usuarios a trav\u00e9s de comentarios u otras herramientas de blogging o de participaci\u00f3n que pueda haber.\n        <\/p>\n<p>\n        El mero acceso a este Sitio Web no supone entablar ning\u00fan tipo de relaci\u00f3n de car\u00e1cter comercial entre Blog de  y el Usuario.\n        <\/p>\n<p>\n        El Usuario declara ser mayor de edad y disponer de la capacidad jur\u00eddica suficiente para vincularse por las presentes Condiciones. Por lo tanto, este Sitio Web de Blog de  no se dirige a menores de edad. Blog de  declina cualquier responsabilidad por el incumplimiento de este requisito.\n        <\/p>\n<p>        &nbsp;<\/p>\n<h3>III. ACCESO Y NAVEGACI\u00d3N EN EL SITIO WEB:<\/h3>\n<h4>EXCLUSI\u00d3N DE GARANT\u00cdAS Y RESPONSABILIDAD<\/h4>\n<p>\n        Blog de  no garantiza la continuidad, disponibilidad y utilidad del Sitio Web, ni de los Contenidos o Servicios. Blog de  har\u00e1 todo lo posible por el buen funcionamiento del Sitio Web, sin embargo, no se responsabiliza ni garantiza que el acceso a este Sitio Web no vaya a ser ininterrumpido o que est\u00e9 libre de error.\n        <\/p>\n<p>\n        Tampoco se responsabiliza o garantiza que el contenido o software al que pueda accederse a trav\u00e9s de este Sitio Web, est\u00e9 libre de error o cause un da\u00f1o al sistema inform\u00e1tico (software y hardware) del Usuario. En ning\u00fan caso Blog de  ser\u00e1 responsable por las p\u00e9rdidas, da\u00f1os o perjuicios de cualquier tipo que surjan por el acceso, navegaci\u00f3n y el uso del Sitio Web, incluy\u00e9ndose, pero no limit\u00e1ndose, a los ocasionados a los sistemas inform\u00e1ticos o los provocados por la introducci\u00f3n de virus.\n        <\/p>\n<p>\n        Blog de  tampoco se hace responsable de los da\u00f1os que pudiesen ocasionarse a los usuarios por un uso inadecuado de este Sitio Web. En particular, no se hace responsable en modo alguno de las ca\u00eddas, interrupciones, falta o defecto de las telecomunicaciones que pudieran ocurrir.\n        <\/p>\n<p>        &nbsp;<\/p>\n<h3>IV. POL\u00cdTICA DE ENLACES<\/h3>\n<p>\n        Se informa que el Sitio Web de Blog de  pone o puede poner a disposici\u00f3n de los Usuarios medios de enlace (como, entre otros, links, banners, botones), directorios y motores de b\u00fasqueda que permiten a los Usuarios acceder a sitios web pertenecientes y\/o gestionados por terceros.\n        <\/p>\n<p>\n            La instalaci\u00f3n de estos enlaces, directorios y motores de b\u00fasqueda en el Sitio Web tiene por objeto facilitar a los Usuarios la b\u00fasqueda de y acceso a la informaci\u00f3n disponible en Internet, sin que pueda considerarse una sugerencia, recomendaci\u00f3n o invitaci\u00f3n para la visita de los mismos.\n        <\/p>\n<p>\n        Blog de  no ofrece ni comercializa por s\u00ed ni por medio de terceros los productos y\/o servicios disponibles en dichos sitios enlazados.<\/p>\n<p>\n        Asimismo, tampoco garantizar\u00e1 la disponibilidad t\u00e9cnica, exactitud, veracidad, validez o legalidad de sitios ajenos a su propiedad a los que se pueda acceder por medio de los enlaces.<\/p>\n<p>\n        Blog de  en ning\u00fan caso revisar\u00e1 o controlar\u00e1 el contenido de otros sitios web, as\u00ed como tampoco aprueba, examina ni hace propios los productos y servicios, contenidos, archivos y cualquier otro material existente en los referidos sitios enlazados.<\/p>\n<p>\n        Blog de  no asume ninguna responsabilidad por los da\u00f1os y perjuicios que pudieran producirse por el acceso, uso, calidad o licitud de los contenidos, comunicaciones, opiniones, productos y servicios de los sitios web no gestionados por Blog de  y que sean enlazados en este Sitio Web.<\/p>\n<p>\n        El Usuario o tercero que realice un hiperv\u00ednculo desde una p\u00e1gina web de otro, distinto, sitio web al Sitio Web de Blog de  deber\u00e1 saber que:<\/p>\n<p>\n        No se permite la reproducci\u00f3n \u2014total o parcialmente\u2014 de ninguno de los Contenidos y\/o Servicios del Sitio Web sin autorizaci\u00f3n expresa de Blog de .<\/p>\n<p>\n       No se permite tampoco ninguna manifestaci\u00f3n falsa, inexacta o incorrecta sobre el Sitio Web de Blog de , ni sobre los Contenidos y\/o Servicios del mismo.\n       <\/p>\n<p>\n        A excepci\u00f3n del hiperv\u00ednculo, el sitio web en el que se establezca dicho hiperenlace no contendr\u00e1 ning\u00fan elemento, de este Sitio Web, protegido como propiedad intelectual por el ordenamiento jur\u00eddico espa\u00f1ol, salvo autorizaci\u00f3n expresa de Blog de .<\/p>\n<p>\n        El establecimiento del hiperv\u00ednculo no implicar\u00e1 la existencia de relaciones entre Blog de  y el titular del sitio web desde el cual se realice, ni el conocimiento y aceptaci\u00f3n de Blog de  de los contenidos, servicios y\/o actividades ofrecidas en dicho sitio web, y viceversa.<\/p>\n<p>        &nbsp;<\/p>\n<h3>V. PROPIEDAD INTELECTUAL E INDUSTRIAL<\/h3>\n<p>\n        Blog de  por s\u00ed o como parte cesionaria, es titular de todos los derechos de propiedad intelectual e industrial del Sitio Web, as\u00ed como de los elementos contenidos en el mismo (a t\u00edtulo enunciativo y no exhaustivo, im\u00e1genes, sonido, audio, v\u00eddeo, software o textos, marcas o logotipos, combinaciones de colores, estructura y dise\u00f1o, selecci\u00f3n de materiales usados, programas de ordenador necesarios para su funcionamiento, acceso y uso, etc.). Ser\u00e1n, por consiguiente, obras protegidas como propiedad intelectual por el ordenamiento jur\u00eddico espa\u00f1ol, si\u00e9ndoles aplicables tanto la normativa espa\u00f1ola y comunitaria en este campo, como los tratados internacionales relativos a la materia y suscritos por Espa\u00f1a.<\/p>\n<p>\n        Todos los derechos reservados. En virtud de lo dispuesto en la Ley de Propiedad Intelectual, quedan expresamente prohibidas la reproducci\u00f3n, la distribuci\u00f3n y la comunicaci\u00f3n p\u00fablica, incluida su modalidad de puesta a disposici\u00f3n, de la totalidad o parte de los contenidos de esta p\u00e1gina web, con fines comerciales, en cualquier soporte y por cualquier medio t\u00e9cnico, sin la autorizaci\u00f3n de Blog de .<\/p>\n<p>\n        El Usuario se compromete a respetar los derechos de propiedad intelectual e industrial de Blog de . Podr\u00e1 visualizar los elementos del Sitio Web o incluso imprimirlos, copiarlos y almacenarlos en el disco duro de su ordenador o en cualquier otro soporte f\u00edsico siempre y cuando sea, exclusivamente, para su uso personal. El Usuario, sin embargo, no podr\u00e1 suprimir, alterar, o manipular cualquier dispositivo de protecci\u00f3n o sistema de seguridad que estuviera instalado en el Sitio Web.<\/p>\n<p>\n        En caso de que el Usuario o tercero considere que cualquiera de los Contenidos del Sitio Web suponga una violaci\u00f3n de los derechos de protecci\u00f3n de la propiedad intelectual, deber\u00e1 comunicarlo inmediatamente a Blog de  a trav\u00e9s de los datos de contacto del apartado de INFORMACI\u00d3N GENERAL de este Aviso Legal y Condiciones Generales de Uso.\n        <\/p>\n<p>        &nbsp;<\/p>\n<h3>VI. ACCIONES LEGALES, LEGISLACI\u00d3N APLICABLE Y JURISDICCI\u00d3N<\/h3>\n<p>\n        Blog de  se reserva la facultad de presentar las acciones civiles o penales que considere necesarias por la utilizaci\u00f3n indebida del Sitio Web y Contenidos, o por el incumplimiento de las presentes Condiciones.<\/p>\n<p>\n        La relaci\u00f3n entre el Usuario y Blog de  se regir\u00e1 por la normativa vigente y de aplicaci\u00f3n en el territorio espa\u00f1ol. De surgir cualquier controversia en relaci\u00f3n con la interpretaci\u00f3n y\/o a la aplicaci\u00f3n de estas Condiciones las partes someter\u00e1n sus conflictos a la jurisdicci\u00f3n ordinaria someti\u00e9ndose a los jueces y tribunales que correspondan conforme a derecho.<\/p>\n<p>\n        Este documento de Aviso Legal y Condiciones Generales de uso del sitio web ha sido creado mediante el generador de plantilla de aviso legal y condiciones de uso online el d\u00eda 18\/02\/2024.\n        <\/p>\n                    <\/div>\r\n                                    <\/div>\r\n            <\/div>\r\n        <\/div>\r\n    <\/div>\r\n<\/section>\r\n<style>\r\n    .text_content_text_1_1 h1 {\r\n        padding-bottom: 60px;\r\n        font-size: var(--tamano1-font-size);\r\n        font-weight: var(--tamano1-font-weight);\r\n        line-height: var(--tamano1-line-height);\r\n        letter-spacing: var(--tamano1-letter-spacing);\r\n        font-family: var(--tamano1-font-family);\r\n        color: var(--color-2-headings-dark);\r\n    }\r\n\r\n    .text_content_text_1_1 h2 {\r\n        padding-bottom: 60px;\r\n        font-size: var(--tamano2-font-size);\r\n        font-weight: var(--tamano2-font-weight);\r\n        line-height: var(--tamano2-line-height);\r\n        letter-spacing: var(--tamano2-letter-spacing);\r\n        font-family: var(--tamano2-font-family);\r\n        color: var(--color-2-headings-dark);\r\n    }\r\n\r\n    .text_content_text_1_1 h3 {\r\n        padding-bottom: 60px;\r\n        font-size: var(--tamano3-font-size);\r\n        font-weight: var(--tamano3-font-weight);\r\n        line-height: var(--tamano3-line-height);\r\n        letter-spacing: var(--tamano3-letter-spacing);\r\n        font-family: var(--tamano3-font-family);\r\n        color: var(--color-2-headings-dark);\r\n    }\r\n\r\n    .text_content_text_1_1 h4 {\r\n        padding-bottom: 60px;\r\n        font-size: var(--tamano4-font-size);\r\n        font-weight: var(--tamano4-font-weight);\r\n        line-height: var(--tamano4-line-height);\r\n        letter-spacing: var(--tamano4-letter-spacing);\r\n        font-family: var(--tamano4-font-family);\r\n        color: var(--color-2-headings-dark);\r\n    }\r\n\r\n    .text_content_text_1_1 ul,\r\n    .text_content_text_1_1 ol {\r\n        padding-left: 20px;\r\n    }\r\n\r\n    .text_content_text_1_1 .row .col {\r\n        padding-top: 75px;\r\n        width: 100%;\r\n    }\r\n\r\n\r\n    .text_content_text_1_1 .texto {\r\n        margin-bottom: 50px;\r\n    }\r\n\r\n    .text_content_text_1_1 .texto * {\r\n        padding-bottom: 20px;\r\n    }\r\n\r\n\r\n    .text_content_text_1_1 .row {\r\n        display: flex;\r\n        gap: 0px;\r\n    }\r\n\r\n    .text_content_text_1_1 {\r\n        position: relative;\r\n        background-position: center;\r\n        background-repeat: no-repeat;\r\n        background-size: cover;\r\n        padding: 81px 150px;\r\n        margin-top: -1px;\r\n    }\r\n\r\n    @media (max-width:1750px) {\r\n        .text_content_text_1_1 .row {\r\n            gap: 100px;\r\n        }\r\n    }\r\n\r\n    @media (max-width:1550px) {\r\n        .text_content_text_1_1 {\r\n            padding-left: 50px;\r\n            padding-right: 50px;\r\n        }\r\n    }\r\n\r\n    @media (max-width:1350px) {\r\n        .text_content_text_1_1 .row {\r\n            gap: 30px;\r\n        }\r\n    }\r\n\r\n    @media (max-width:1200px) {\r\n        .text_content_text_1_1 {\r\n            padding-left: 0;\r\n            padding-right: 0;\r\n        }\r\n    }\r\n\r\n    @media (max-width:992px) {\r\n        .text_content_text_1_1 .row .col-left {\r\n            padding-top: 0;\r\n            max-width: 100%;\r\n        }\r\n\r\n        .text_content_text_1_1 .texto {\r\n            margin-bottom: 35px;\r\n        }\r\n\r\n        .text_content_text_1_1 h2 {\r\n            padding-bottom: 40px;\r\n        }\r\n\r\n        .text_content_text_1_1 {\r\n            padding: 40px 0;\r\n        }\r\n\r\n        .text_content_text_1_1 h1 {\r\n            font-size: var(--tamano1-font-size-mobile);\r\n        }\r\n\r\n        .text_content_text_1_1 h2 {\r\n            font-size: var(--tamano2-font-size-mobile);\r\n        }\r\n\r\n        .text_content_text_1_1 h3 {\r\n            font-size: var(--tamano3-font-size-mobile);\r\n        }\r\n\r\n        .text_content_text_1_1 h4 {\r\n            font-size: var(--tamano4-font-size-mobile);\r\n        }\r\n    }\r\n<\/style>\r\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"open","ping_status":"closed","template":"","meta":{"_acf_changed":false,"iawp_total_views":0,"footnotes":""},"class_list":["post-403","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Aviso Legal y Condiciones - ROALDA GROUP<\/title>\n<meta name=\"description\" content=\"Consulta el aviso legal y las condiciones de uso del sitio web de ROALDA GROUP para navegar con seguridad y conocer tus derechos.\" \/>\n<meta name=\"robots\" content=\"noindex, nofollow\" \/>\n<meta property=\"og:locale\" content=\"ca_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Aviso Legal y Condiciones - ROALDA GROUP\" \/>\n<meta property=\"og:description\" content=\"Consulta el aviso legal y las condiciones de uso del sitio web de ROALDA GROUP para navegar con seguridad y conocer tus derechos.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/roaldagroup.com\/ca\/aviso-legal\/\" \/>\n<meta property=\"og:site_name\" content=\"ROALDA GROUP\" \/>\n<meta property=\"article:modified_time\" content=\"2025-10-09T07:28:42+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Aviso Legal y Condiciones - ROALDA GROUP","description":"Consulta el aviso legal y las condiciones de uso del sitio web de ROALDA GROUP para navegar con seguridad y conocer tus derechos.","robots":{"index":"noindex","follow":"nofollow"},"og_locale":"ca_ES","og_type":"article","og_title":"Aviso Legal y Condiciones - ROALDA GROUP","og_description":"Consulta el aviso legal y las condiciones de uso del sitio web de ROALDA GROUP para navegar con seguridad y conocer tus derechos.","og_url":"https:\/\/roaldagroup.com\/ca\/aviso-legal\/","og_site_name":"ROALDA GROUP","article_modified_time":"2025-10-09T07:28:42+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/roaldagroup.com\/ca\/aviso-legal\/","url":"https:\/\/roaldagroup.com\/ca\/aviso-legal\/","name":"Aviso Legal y Condiciones - ROALDA GROUP","isPartOf":{"@id":"https:\/\/roaldagroup.com\/ca\/#website"},"datePublished":"2024-07-24T09:32:46+00:00","dateModified":"2025-10-09T07:28:42+00:00","description":"Consulta el aviso legal y las condiciones de uso del sitio web de ROALDA GROUP para navegar con seguridad y conocer tus derechos.","breadcrumb":{"@id":"https:\/\/roaldagroup.com\/ca\/aviso-legal\/#breadcrumb"},"inLanguage":"ca","potentialAction":[{"@type":"ReadAction","target":["https:\/\/roaldagroup.com\/ca\/aviso-legal\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/roaldagroup.com\/ca\/aviso-legal\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/roaldagroup.com\/ca\/"},{"@type":"ListItem","position":2,"name":"Aviso legal"}]},{"@type":"WebSite","@id":"https:\/\/roaldagroup.com\/ca\/#website","url":"https:\/\/roaldagroup.com\/ca\/","name":"ROALDA GROUP","description":"","publisher":{"@id":"https:\/\/roaldagroup.com\/ca\/#\/schema\/person\/0e1b9d5d16aaa559efbf42443b6b4a6e"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/roaldagroup.com\/ca\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"ca"},{"@type":["Person","Organization"],"@id":"https:\/\/roaldagroup.com\/ca\/#\/schema\/person\/0e1b9d5d16aaa559efbf42443b6b4a6e","name":"Cliente Apellidos","image":{"@type":"ImageObject","inLanguage":"ca","@id":"https:\/\/roaldagroup.com\/wp-content\/uploads\/2024\/07\/668b9857b2ced_Roalda_Group-removebg-preview.png","url":"https:\/\/roaldagroup.com\/wp-content\/uploads\/2024\/07\/668b9857b2ced_Roalda_Group-removebg-preview.png","contentUrl":"https:\/\/roaldagroup.com\/wp-content\/uploads\/2024\/07\/668b9857b2ced_Roalda_Group-removebg-preview.png","width":439,"height":568,"caption":"Cliente Apellidos"},"logo":{"@id":"https:\/\/roaldagroup.com\/wp-content\/uploads\/2024\/07\/668b9857b2ced_Roalda_Group-removebg-preview.png"}}]}},"_links":{"self":[{"href":"https:\/\/roaldagroup.com\/ca\/wp-json\/wp\/v2\/pages\/403","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/roaldagroup.com\/ca\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/roaldagroup.com\/ca\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/roaldagroup.com\/ca\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/roaldagroup.com\/ca\/wp-json\/wp\/v2\/comments?post=403"}],"version-history":[{"count":1,"href":"https:\/\/roaldagroup.com\/ca\/wp-json\/wp\/v2\/pages\/403\/revisions"}],"predecessor-version":[{"id":4259,"href":"https:\/\/roaldagroup.com\/ca\/wp-json\/wp\/v2\/pages\/403\/revisions\/4259"}],"wp:attachment":[{"href":"https:\/\/roaldagroup.com\/ca\/wp-json\/wp\/v2\/media?parent=403"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}